{"id":2716,"date":"2024-08-28T17:04:42","date_gmt":"2024-08-28T17:04:42","guid":{"rendered":"https:\/\/www.b2bcfo.com\/dave-ziozios\/organizations\/wharton-online\/"},"modified":"2024-08-28T17:04:42","modified_gmt":"2024-08-28T17:04:42","slug":"wharton-online","status":"publish","type":"organizations","link":"https:\/\/www.b2bcfo.com\/dave-ziozios\/organizations\/wharton-online\/","title":{"rendered":"Wharton Online"},"template":"","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","cybocfi_hide_featured_image":"","_members_access_role":[],"_members_access_error":""},"org_type":[9],"class_list":["post-2716","organizations","type-organizations","status-publish","hentry","org_type-certification"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wharton Online - Dave Ziozios<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wharton Online - Dave Ziozios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b2bcfo.com\/dave-ziozios\/organizations\/wharton-online\/\" \/>\n<meta property=\"og:site_name\" content=\"Dave Ziozios\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/organizations\\\/wharton-online\\\/\",\"url\":\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/organizations\\\/wharton-online\\\/\",\"name\":\"Wharton Online - Dave Ziozios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/#website\"},\"datePublished\":\"2024-08-28T17:04:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/organizations\\\/wharton-online\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/organizations\\\/wharton-online\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/organizations\\\/wharton-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wharton Online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/#website\",\"url\":\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/\",\"name\":\"Dave Ziozios\",\"description\":\"B2B CFO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b2bcfo.com\\\/dave-ziozios\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wharton Online - Dave Ziozios","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Wharton Online - Dave Ziozios","og_url":"https:\/\/www.b2bcfo.com\/dave-ziozios\/organizations\/wharton-online\/","og_site_name":"Dave Ziozios","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b2bcfo.com\/dave-ziozios\/organizations\/wharton-online\/","url":"https:\/\/www.b2bcfo.com\/dave-ziozios\/organizations\/wharton-online\/","name":"Wharton Online - Dave Ziozios","isPartOf":{"@id":"https:\/\/www.b2bcfo.com\/dave-ziozios\/#website"},"datePublished":"2024-08-28T17:04:42+00:00","breadcrumb":{"@id":"https:\/\/www.b2bcfo.com\/dave-ziozios\/organizations\/wharton-online\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b2bcfo.com\/dave-ziozios\/organizations\/wharton-online\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.b2bcfo.com\/dave-ziozios\/organizations\/wharton-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b2bcfo.com\/dave-ziozios\/"},{"@type":"ListItem","position":2,"name":"Wharton Online"}]},{"@type":"WebSite","@id":"https:\/\/www.b2bcfo.com\/dave-ziozios\/#website","url":"https:\/\/www.b2bcfo.com\/dave-ziozios\/","name":"Dave Ziozios","description":"B2B CFO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b2bcfo.com\/dave-ziozios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.b2bcfo.com\/dave-ziozios\/wp-json\/wp\/v2\/organizations\/2716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b2bcfo.com\/dave-ziozios\/wp-json\/wp\/v2\/organizations"}],"about":[{"href":"https:\/\/www.b2bcfo.com\/dave-ziozios\/wp-json\/wp\/v2\/types\/organizations"}],"wp:attachment":[{"href":"https:\/\/www.b2bcfo.com\/dave-ziozios\/wp-json\/wp\/v2\/media?parent=2716"}],"wp:term":[{"taxonomy":"org_type","embeddable":true,"href":"https:\/\/www.b2bcfo.com\/dave-ziozios\/wp-json\/wp\/v2\/org_type?post=2716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}