{"id":2588,"date":"2024-01-05T17:57:52","date_gmt":"2024-01-05T17:57:52","guid":{"rendered":"https:\/\/www.b2bcfo.com\/mark-shearer\/organizations\/wofford-college\/"},"modified":"2024-01-05T17:57:52","modified_gmt":"2024-01-05T17:57:52","slug":"wofford-college","status":"publish","type":"organizations","link":"https:\/\/www.b2bcfo.com\/mark-shearer\/organizations\/wofford-college\/","title":{"rendered":"Wofford College"},"template":"","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","cybocfi_hide_featured_image":"","_members_access_role":[],"_members_access_error":""},"org_type":[8],"class_list":["post-2588","organizations","type-organizations","status-publish","hentry","org_type-education"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wofford College - Mark Shearer<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wofford College - Mark Shearer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.b2bcfo.com\/mark-shearer\/organizations\/wofford-college\/\" \/>\n<meta property=\"og:site_name\" content=\"Mark Shearer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/organizations\\\/wofford-college\\\/\",\"url\":\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/organizations\\\/wofford-college\\\/\",\"name\":\"Wofford College - Mark Shearer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/#website\"},\"datePublished\":\"2024-01-05T17:57:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/organizations\\\/wofford-college\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/organizations\\\/wofford-college\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/organizations\\\/wofford-college\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wofford College\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/#website\",\"url\":\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/\",\"name\":\"Mark Shearer\",\"description\":\"B2B CFO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.b2bcfo.com\\\/mark-shearer\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wofford College - Mark Shearer","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Wofford College - Mark Shearer","og_url":"https:\/\/www.b2bcfo.com\/mark-shearer\/organizations\/wofford-college\/","og_site_name":"Mark Shearer","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.b2bcfo.com\/mark-shearer\/organizations\/wofford-college\/","url":"https:\/\/www.b2bcfo.com\/mark-shearer\/organizations\/wofford-college\/","name":"Wofford College - Mark Shearer","isPartOf":{"@id":"https:\/\/www.b2bcfo.com\/mark-shearer\/#website"},"datePublished":"2024-01-05T17:57:52+00:00","breadcrumb":{"@id":"https:\/\/www.b2bcfo.com\/mark-shearer\/organizations\/wofford-college\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.b2bcfo.com\/mark-shearer\/organizations\/wofford-college\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.b2bcfo.com\/mark-shearer\/organizations\/wofford-college\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.b2bcfo.com\/mark-shearer\/"},{"@type":"ListItem","position":2,"name":"Wofford College"}]},{"@type":"WebSite","@id":"https:\/\/www.b2bcfo.com\/mark-shearer\/#website","url":"https:\/\/www.b2bcfo.com\/mark-shearer\/","name":"Mark Shearer","description":"B2B CFO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.b2bcfo.com\/mark-shearer\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.b2bcfo.com\/mark-shearer\/wp-json\/wp\/v2\/organizations\/2588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.b2bcfo.com\/mark-shearer\/wp-json\/wp\/v2\/organizations"}],"about":[{"href":"https:\/\/www.b2bcfo.com\/mark-shearer\/wp-json\/wp\/v2\/types\/organizations"}],"wp:attachment":[{"href":"https:\/\/www.b2bcfo.com\/mark-shearer\/wp-json\/wp\/v2\/media?parent=2588"}],"wp:term":[{"taxonomy":"org_type","embeddable":true,"href":"https:\/\/www.b2bcfo.com\/mark-shearer\/wp-json\/wp\/v2\/org_type?post=2588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}